{"id":14062,"count":0,"description":"","link":"https:\/\/aw-chesterton.eu\/pl\/products\/szczeliwo-do-pomp\/","name":"Szczeliwo do pomp","slug":"szczeliwo-do-pomp","taxonomy":"product_category","parent":14034,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Szczeliwo do pomp Archive - A.W. Chesterton Company \u2013 EU<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aw-chesterton.eu\/pl\/products\/szczeliwo-do-pomp\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Szczeliwo do pomp Archive - A.W. Chesterton Company \u2013 EU\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aw-chesterton.eu\/pl\/products\/szczeliwo-do-pomp\/\" \/>\n<meta property=\"og:site_name\" content=\"A.W. Chesterton Company \u2013 EU\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/pl\\\/products\\\/szczeliwo-do-pomp\\\/\",\"url\":\"https:\\\/\\\/aw-chesterton.eu\\\/pl\\\/products\\\/szczeliwo-do-pomp\\\/\",\"name\":\"Szczeliwo do pomp Archive - A.W. Chesterton Company \u2013 EU\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/pl\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/pl\\\/products\\\/szczeliwo-do-pomp\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/pl\\\/products\\\/szczeliwo-do-pomp\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aw-chesterton.eu\\\/pl\\\/strona-glowna\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Szczeliwa mechaniczne i uszczelki\u00a0p\u0142askie\",\"item\":\"https:\\\/\\\/aw-chesterton.eu\\\/pl\\\/products\\\/szczeliwa-mechaniczne-i-uszczelki-plaskie\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Szczeliwo do pomp\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/pl\\\/#website\",\"url\":\"https:\\\/\\\/aw-chesterton.eu\\\/pl\\\/\",\"name\":\"A.W. Chesterton Company \u2013 EU\",\"description\":\"A.W. Chesterton Company \u2013 EU\",\"publisher\":{\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/pl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aw-chesterton.eu\\\/pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/pl\\\/#organization\",\"name\":\"Chesterton Deutschland\",\"url\":\"https:\\\/\\\/aw-chesterton.eu\\\/pl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/pl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aw-chesterton.eu\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Chesterton_Logo_CMYK_Vect.png\",\"contentUrl\":\"https:\\\/\\\/aw-chesterton.eu\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Chesterton_Logo_CMYK_Vect.png\",\"width\":1200,\"height\":218,\"caption\":\"Chesterton Deutschland\"},\"image\":{\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/pl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Szczeliwo do pomp Archive - A.W. Chesterton Company \u2013 EU","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aw-chesterton.eu\/pl\/products\/szczeliwo-do-pomp\/","og_locale":"pl_PL","og_type":"article","og_title":"Szczeliwo do pomp Archive - A.W. Chesterton Company \u2013 EU","og_url":"https:\/\/aw-chesterton.eu\/pl\/products\/szczeliwo-do-pomp\/","og_site_name":"A.W. Chesterton Company \u2013 EU","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/aw-chesterton.eu\/pl\/products\/szczeliwo-do-pomp\/","url":"https:\/\/aw-chesterton.eu\/pl\/products\/szczeliwo-do-pomp\/","name":"Szczeliwo do pomp Archive - A.W. Chesterton Company \u2013 EU","isPartOf":{"@id":"https:\/\/aw-chesterton.eu\/pl\/#website"},"breadcrumb":{"@id":"https:\/\/aw-chesterton.eu\/pl\/products\/szczeliwo-do-pomp\/#breadcrumb"},"inLanguage":"pl-PL"},{"@type":"BreadcrumbList","@id":"https:\/\/aw-chesterton.eu\/pl\/products\/szczeliwo-do-pomp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aw-chesterton.eu\/pl\/strona-glowna\/"},{"@type":"ListItem","position":2,"name":"Szczeliwa mechaniczne i uszczelki\u00a0p\u0142askie","item":"https:\/\/aw-chesterton.eu\/pl\/products\/szczeliwa-mechaniczne-i-uszczelki-plaskie\/"},{"@type":"ListItem","position":3,"name":"Szczeliwo do pomp"}]},{"@type":"WebSite","@id":"https:\/\/aw-chesterton.eu\/pl\/#website","url":"https:\/\/aw-chesterton.eu\/pl\/","name":"A.W. Chesterton Company \u2013 EU","description":"A.W. Chesterton Company \u2013 EU","publisher":{"@id":"https:\/\/aw-chesterton.eu\/pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aw-chesterton.eu\/pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Organization","@id":"https:\/\/aw-chesterton.eu\/pl\/#organization","name":"Chesterton Deutschland","url":"https:\/\/aw-chesterton.eu\/pl\/","logo":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/aw-chesterton.eu\/pl\/#\/schema\/logo\/image\/","url":"https:\/\/aw-chesterton.eu\/wp-content\/uploads\/2026\/03\/Chesterton_Logo_CMYK_Vect.png","contentUrl":"https:\/\/aw-chesterton.eu\/wp-content\/uploads\/2026\/03\/Chesterton_Logo_CMYK_Vect.png","width":1200,"height":218,"caption":"Chesterton Deutschland"},"image":{"@id":"https:\/\/aw-chesterton.eu\/pl\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/aw-chesterton.eu\/pl\/wp-json\/wp\/v2\/product_category\/14062","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aw-chesterton.eu\/pl\/wp-json\/wp\/v2\/product_category"}],"about":[{"href":"https:\/\/aw-chesterton.eu\/pl\/wp-json\/wp\/v2\/taxonomies\/product_category"}],"up":[{"embeddable":true,"href":"https:\/\/aw-chesterton.eu\/pl\/wp-json\/wp\/v2\/product_category\/14034"}],"wp:post_type":[{"href":"https:\/\/aw-chesterton.eu\/pl\/wp-json\/wp\/v2\/chesterton_product?product_category=14062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}