{"id":22231,"date":"2018-08-23T11:39:58","date_gmt":"2018-08-23T09:39:58","guid":{"rendered":"https:\/\/aw-chesterton.eu\/products\/uncategorized\/r22kn5-joint-tournant-en-deux-parties-2\/"},"modified":"2026-07-22T22:25:33","modified_gmt":"2026-07-22T20:25:33","slug":"r22kn5-joint-tournant-en-deux-parties-2","status":"publish","type":"chesterton_product","link":"https:\/\/aw-chesterton.eu\/pl\/products\/bearing-and-gearbox-protection\/r22kn5-joint-tournant-en-deux-parties-2\/","title":{"rendered":"R22KN5"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Wysokowydajna, sprawdzona konstrukcja dla wolnoobrotowych zastosowa\u0144, nara\u017conych na nadmierne luzy promieniowe wa\u0142u.<\/p>\n<ul class=\"wp-block-list\"><li>Spr\u0119\u017cysta konstrukcja dynamicznej wargi uszczelniaj\u0105cej kompensuje znaczne bicie wa\u0142\u00f3w i tulei<\/li><li>Dzielona konstrukcja u\u0142atwia monta\u017c<\/li><li>Masywna konstrukcja wargi statycznej zapewnia pewne mocowanie w rowku i stabilno\u015b\u0107 uszczelnienia<\/li><li>Konstrukcja odporna na \u015bcieranie zapewnia wytrzyma\u0142o\u015b\u0107 w trudnym \u015brodowisku pracy<\/li><\/ul>\n\n<h3 class=\"chesterton-section-heading\">Product Characteristics Parameters<\/h3>\n<table class=\"chesterton-product-data__table\"><tbody><tr><td>Material (designation)<\/td><td>Size Range* mm (inch)<\/td><td>Temperature\u02daC (\u02daF)<\/td><td>Pressure MPa (psi)<\/td><td>Speed m\/s (ft\/min)<\/td><\/tr><tr><td>AWC704 (FKM)<\/td><td>6 \u2500 304.8 (1\/4 \u2500 12)<\/td><td>-30 \u2500 200 (-20 \u2500 400)<\/td><td>34.5 (5000)<\/td><td>1.5 (300)<\/td><\/tr><tr class=\"is-alt\"><td>AWC800 (EU)<\/td><td>6 \u2500 2540 (1\/4 \u2500 100)<\/td><td>-50 \u2500 85 (-60 \u2500 185)<\/td><td>103.5 (15000)<\/td><td>1 (200)<\/td><\/tr><tr><td>AWC830 (EU)<\/td><td>6 \u2500 254 (1\/4 \u2500 10)<\/td><td>-35 \u2500 75 (-30 \u2500 175)<\/td><td>52 (7500)<\/td><td>0.9 (185)<\/td><\/tr><tr class=\"is-alt\"><td>AWC860 (EU)<\/td><td>6 \u2500 508 (1\/4 \u2500 20)<\/td><td>-50 \u2500 120 (-60 \u2500 250)<\/td><td>103.5 (15000)<\/td><td>1.25 (250)<\/td><\/tr><tr><td colspan=\"5\">Pending on the seal height and cross section, the split joint can be interlock arrow cutt or butt cut.<\/td><\/tr><tr><td colspan=\"5\">* Please contact your Chesterton representative for larger sizes<\/td><\/tr><\/tbody><\/table>","protected":false},"excerpt":{"rendered":"<p>Dzielone uszczelnienie wa\u0142\u00f3w i osi obrotowych<\/p>\n","protected":false},"featured_media":8476,"template":"","product_category":[13320,13319],"class_list":["post-22231","chesterton_product","type-chesterton_product","status-publish","has-post-thumbnail","hentry","product_category-bearing-and-gearbox-protection","product_category-rotary-seals"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>R22KN5 - A.W. Chesterton Company \u2013 EU<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aw-chesterton.eu\/pl\/products\/bearing-and-gearbox-protection\/r22kn5-joint-tournant-en-deux-parties-2\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R22KN5 - A.W. Chesterton Company \u2013 EU\" \/>\n<meta property=\"og:description\" content=\"Dzielone uszczelnienie wa\u0142\u00f3w i osi obrotowych\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aw-chesterton.eu\/pl\/products\/bearing-and-gearbox-protection\/r22kn5-joint-tournant-en-deux-parties-2\/\" \/>\n<meta property=\"og:site_name\" content=\"A.W. Chesterton Company \u2013 EU\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-22T20:25:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aw-chesterton.eu\/wp-content\/uploads\/2025\/01\/22k5_seal.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"968\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Szacowany czas czytania\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuta\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/pl\\\/products\\\/bearing-and-gearbox-protection\\\/r22kn5-joint-tournant-en-deux-parties-2\\\/\",\"url\":\"https:\\\/\\\/aw-chesterton.eu\\\/pl\\\/products\\\/bearing-and-gearbox-protection\\\/r22kn5-joint-tournant-en-deux-parties-2\\\/\",\"name\":\"R22KN5 - A.W. Chesterton Company \u2013 EU\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/pl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/pl\\\/products\\\/bearing-and-gearbox-protection\\\/r22kn5-joint-tournant-en-deux-parties-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/pl\\\/products\\\/bearing-and-gearbox-protection\\\/r22kn5-joint-tournant-en-deux-parties-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aw-chesterton.eu\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/22k5_seal.png\",\"datePublished\":\"2018-08-23T09:39:58+00:00\",\"dateModified\":\"2026-07-22T20:25:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/pl\\\/products\\\/bearing-and-gearbox-protection\\\/r22kn5-joint-tournant-en-deux-parties-2\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aw-chesterton.eu\\\/pl\\\/products\\\/bearing-and-gearbox-protection\\\/r22kn5-joint-tournant-en-deux-parties-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/pl\\\/products\\\/bearing-and-gearbox-protection\\\/r22kn5-joint-tournant-en-deux-parties-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aw-chesterton.eu\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/22k5_seal.png\",\"contentUrl\":\"https:\\\/\\\/aw-chesterton.eu\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/22k5_seal.png\",\"width\":1024,\"height\":968},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/pl\\\/products\\\/bearing-and-gearbox-protection\\\/r22kn5-joint-tournant-en-deux-parties-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aw-chesterton.eu\\\/pl\\\/strona-glowna\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uszczelnienia polimerowe\",\"item\":\"https:\\\/\\\/aw-chesterton.eu\\\/pl\\\/products\\\/uszczelnienia-polimerowe\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ochrona \u0142o\u017cysk i przek\u0142adni\",\"item\":\"https:\\\/\\\/aw-chesterton.eu\\\/pl\\\/products\\\/ochrona-lozysk-i-przekladni\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"R22KN5\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/pl\\\/#website\",\"url\":\"https:\\\/\\\/aw-chesterton.eu\\\/pl\\\/\",\"name\":\"A.W. Chesterton Company \u2013 EU\",\"description\":\"A.W. Chesterton Company \u2013 EU\",\"publisher\":{\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/pl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aw-chesterton.eu\\\/pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/pl\\\/#organization\",\"name\":\"Chesterton Deutschland\",\"url\":\"https:\\\/\\\/aw-chesterton.eu\\\/pl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/pl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aw-chesterton.eu\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Chesterton_Logo_CMYK_Vect.png\",\"contentUrl\":\"https:\\\/\\\/aw-chesterton.eu\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Chesterton_Logo_CMYK_Vect.png\",\"width\":1200,\"height\":218,\"caption\":\"Chesterton Deutschland\"},\"image\":{\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/pl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R22KN5 - A.W. Chesterton Company \u2013 EU","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aw-chesterton.eu\/pl\/products\/bearing-and-gearbox-protection\/r22kn5-joint-tournant-en-deux-parties-2\/","og_locale":"pl_PL","og_type":"article","og_title":"R22KN5 - A.W. Chesterton Company \u2013 EU","og_description":"Dzielone uszczelnienie wa\u0142\u00f3w i osi obrotowych","og_url":"https:\/\/aw-chesterton.eu\/pl\/products\/bearing-and-gearbox-protection\/r22kn5-joint-tournant-en-deux-parties-2\/","og_site_name":"A.W. Chesterton Company \u2013 EU","article_modified_time":"2026-07-22T20:25:33+00:00","og_image":[{"width":1024,"height":968,"url":"https:\/\/aw-chesterton.eu\/wp-content\/uploads\/2025\/01\/22k5_seal.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Szacowany czas czytania":"1 minuta"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/aw-chesterton.eu\/pl\/products\/bearing-and-gearbox-protection\/r22kn5-joint-tournant-en-deux-parties-2\/","url":"https:\/\/aw-chesterton.eu\/pl\/products\/bearing-and-gearbox-protection\/r22kn5-joint-tournant-en-deux-parties-2\/","name":"R22KN5 - A.W. Chesterton Company \u2013 EU","isPartOf":{"@id":"https:\/\/aw-chesterton.eu\/pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aw-chesterton.eu\/pl\/products\/bearing-and-gearbox-protection\/r22kn5-joint-tournant-en-deux-parties-2\/#primaryimage"},"image":{"@id":"https:\/\/aw-chesterton.eu\/pl\/products\/bearing-and-gearbox-protection\/r22kn5-joint-tournant-en-deux-parties-2\/#primaryimage"},"thumbnailUrl":"https:\/\/aw-chesterton.eu\/wp-content\/uploads\/2025\/01\/22k5_seal.png","datePublished":"2018-08-23T09:39:58+00:00","dateModified":"2026-07-22T20:25:33+00:00","breadcrumb":{"@id":"https:\/\/aw-chesterton.eu\/pl\/products\/bearing-and-gearbox-protection\/r22kn5-joint-tournant-en-deux-parties-2\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aw-chesterton.eu\/pl\/products\/bearing-and-gearbox-protection\/r22kn5-joint-tournant-en-deux-parties-2\/"]}]},{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/aw-chesterton.eu\/pl\/products\/bearing-and-gearbox-protection\/r22kn5-joint-tournant-en-deux-parties-2\/#primaryimage","url":"https:\/\/aw-chesterton.eu\/wp-content\/uploads\/2025\/01\/22k5_seal.png","contentUrl":"https:\/\/aw-chesterton.eu\/wp-content\/uploads\/2025\/01\/22k5_seal.png","width":1024,"height":968},{"@type":"BreadcrumbList","@id":"https:\/\/aw-chesterton.eu\/pl\/products\/bearing-and-gearbox-protection\/r22kn5-joint-tournant-en-deux-parties-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aw-chesterton.eu\/pl\/strona-glowna\/"},{"@type":"ListItem","position":2,"name":"Uszczelnienia polimerowe","item":"https:\/\/aw-chesterton.eu\/pl\/products\/uszczelnienia-polimerowe\/"},{"@type":"ListItem","position":3,"name":"Ochrona \u0142o\u017cysk i przek\u0142adni","item":"https:\/\/aw-chesterton.eu\/pl\/products\/ochrona-lozysk-i-przekladni\/"},{"@type":"ListItem","position":4,"name":"R22KN5"}]},{"@type":"WebSite","@id":"https:\/\/aw-chesterton.eu\/pl\/#website","url":"https:\/\/aw-chesterton.eu\/pl\/","name":"A.W. Chesterton Company \u2013 EU","description":"A.W. Chesterton Company \u2013 EU","publisher":{"@id":"https:\/\/aw-chesterton.eu\/pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aw-chesterton.eu\/pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Organization","@id":"https:\/\/aw-chesterton.eu\/pl\/#organization","name":"Chesterton Deutschland","url":"https:\/\/aw-chesterton.eu\/pl\/","logo":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/aw-chesterton.eu\/pl\/#\/schema\/logo\/image\/","url":"https:\/\/aw-chesterton.eu\/wp-content\/uploads\/2026\/03\/Chesterton_Logo_CMYK_Vect.png","contentUrl":"https:\/\/aw-chesterton.eu\/wp-content\/uploads\/2026\/03\/Chesterton_Logo_CMYK_Vect.png","width":1200,"height":218,"caption":"Chesterton Deutschland"},"image":{"@id":"https:\/\/aw-chesterton.eu\/pl\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/aw-chesterton.eu\/pl\/wp-json\/wp\/v2\/chesterton_product\/22231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aw-chesterton.eu\/pl\/wp-json\/wp\/v2\/chesterton_product"}],"about":[{"href":"https:\/\/aw-chesterton.eu\/pl\/wp-json\/wp\/v2\/types\/chesterton_product"}],"version-history":[{"count":3,"href":"https:\/\/aw-chesterton.eu\/pl\/wp-json\/wp\/v2\/chesterton_product\/22231\/revisions"}],"predecessor-version":[{"id":33121,"href":"https:\/\/aw-chesterton.eu\/pl\/wp-json\/wp\/v2\/chesterton_product\/22231\/revisions\/33121"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aw-chesterton.eu\/pl\/wp-json\/wp\/v2\/media\/8476"}],"wp:attachment":[{"href":"https:\/\/aw-chesterton.eu\/pl\/wp-json\/wp\/v2\/media?parent=22231"}],"wp:term":[{"taxonomy":"product_category","embeddable":true,"href":"https:\/\/aw-chesterton.eu\/pl\/wp-json\/wp\/v2\/product_category?post=22231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}