{"id":14059,"count":0,"description":"","link":"https:\/\/aw-chesterton.eu\/fr\/products\/tresse-detancheite-de-pompe\/","name":"Tresse d'\u00e9tanch\u00e9it\u00e9 de pompe","slug":"tresse-detancheite-de-pompe","taxonomy":"product_category","parent":14031,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tresse d&#039;\u00e9tanch\u00e9it\u00e9 de pompe Archive - A.W. Chesterton Company \u2013 EU<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aw-chesterton.eu\/fr\/products\/tresse-detancheite-de-pompe\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tresse d&#039;\u00e9tanch\u00e9it\u00e9 de pompe Archive - A.W. Chesterton Company \u2013 EU\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aw-chesterton.eu\/fr\/products\/tresse-detancheite-de-pompe\/\" \/>\n<meta property=\"og:site_name\" content=\"A.W. Chesterton Company \u2013 EU\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/fr\\\/products\\\/tresse-detancheite-de-pompe\\\/\",\"url\":\"https:\\\/\\\/aw-chesterton.eu\\\/fr\\\/products\\\/tresse-detancheite-de-pompe\\\/\",\"name\":\"Tresse d'\u00e9tanch\u00e9it\u00e9 de pompe Archive - A.W. Chesterton Company \u2013 EU\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/fr\\\/products\\\/tresse-detancheite-de-pompe\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/fr\\\/products\\\/tresse-detancheite-de-pompe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aw-chesterton.eu\\\/fr\\\/page-daccueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tresses d\u2019\u00e9tanch\u00e9it\u00e9 et joints\",\"item\":\"https:\\\/\\\/aw-chesterton.eu\\\/fr\\\/products\\\/tresses-detancheite-et-joints\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tresse d'\u00e9tanch\u00e9it\u00e9 de pompe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/aw-chesterton.eu\\\/fr\\\/\",\"name\":\"A.W. Chesterton Company \u2013 EU\",\"description\":\"A.W. Chesterton Company \u2013 EU\",\"publisher\":{\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aw-chesterton.eu\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/fr\\\/#organization\",\"name\":\"Chesterton Deutschland\",\"url\":\"https:\\\/\\\/aw-chesterton.eu\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aw-chesterton.eu\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Chesterton_Logo_CMYK_Vect.png\",\"contentUrl\":\"https:\\\/\\\/aw-chesterton.eu\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Chesterton_Logo_CMYK_Vect.png\",\"width\":1200,\"height\":218,\"caption\":\"Chesterton Deutschland\"},\"image\":{\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tresse d'\u00e9tanch\u00e9it\u00e9 de pompe Archive - A.W. Chesterton Company \u2013 EU","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aw-chesterton.eu\/fr\/products\/tresse-detancheite-de-pompe\/","og_locale":"fr_FR","og_type":"article","og_title":"Tresse d'\u00e9tanch\u00e9it\u00e9 de pompe Archive - A.W. Chesterton Company \u2013 EU","og_url":"https:\/\/aw-chesterton.eu\/fr\/products\/tresse-detancheite-de-pompe\/","og_site_name":"A.W. Chesterton Company \u2013 EU","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/aw-chesterton.eu\/fr\/products\/tresse-detancheite-de-pompe\/","url":"https:\/\/aw-chesterton.eu\/fr\/products\/tresse-detancheite-de-pompe\/","name":"Tresse d'\u00e9tanch\u00e9it\u00e9 de pompe Archive - A.W. Chesterton Company \u2013 EU","isPartOf":{"@id":"https:\/\/aw-chesterton.eu\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/aw-chesterton.eu\/fr\/products\/tresse-detancheite-de-pompe\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/aw-chesterton.eu\/fr\/products\/tresse-detancheite-de-pompe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aw-chesterton.eu\/fr\/page-daccueil\/"},{"@type":"ListItem","position":2,"name":"Tresses d\u2019\u00e9tanch\u00e9it\u00e9 et joints","item":"https:\/\/aw-chesterton.eu\/fr\/products\/tresses-detancheite-et-joints\/"},{"@type":"ListItem","position":3,"name":"Tresse d'\u00e9tanch\u00e9it\u00e9 de pompe"}]},{"@type":"WebSite","@id":"https:\/\/aw-chesterton.eu\/fr\/#website","url":"https:\/\/aw-chesterton.eu\/fr\/","name":"A.W. Chesterton Company \u2013 EU","description":"A.W. Chesterton Company \u2013 EU","publisher":{"@id":"https:\/\/aw-chesterton.eu\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aw-chesterton.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/aw-chesterton.eu\/fr\/#organization","name":"Chesterton Deutschland","url":"https:\/\/aw-chesterton.eu\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/aw-chesterton.eu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/aw-chesterton.eu\/wp-content\/uploads\/2026\/03\/Chesterton_Logo_CMYK_Vect.png","contentUrl":"https:\/\/aw-chesterton.eu\/wp-content\/uploads\/2026\/03\/Chesterton_Logo_CMYK_Vect.png","width":1200,"height":218,"caption":"Chesterton Deutschland"},"image":{"@id":"https:\/\/aw-chesterton.eu\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/aw-chesterton.eu\/fr\/wp-json\/wp\/v2\/product_category\/14059","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aw-chesterton.eu\/fr\/wp-json\/wp\/v2\/product_category"}],"about":[{"href":"https:\/\/aw-chesterton.eu\/fr\/wp-json\/wp\/v2\/taxonomies\/product_category"}],"up":[{"embeddable":true,"href":"https:\/\/aw-chesterton.eu\/fr\/wp-json\/wp\/v2\/product_category\/14031"}],"wp:post_type":[{"href":"https:\/\/aw-chesterton.eu\/fr\/wp-json\/wp\/v2\/chesterton_product?product_category=14059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}