{"id":9522,"date":"2026-05-12T13:26:53","date_gmt":"2026-05-12T13:26:53","guid":{"rendered":"https:\/\/aw-chesterton.eu\/products\/uncategorized\/617e\/"},"modified":"2026-06-02T12:30:41","modified_gmt":"2026-06-02T10:30:41","slug":"617e","status":"publish","type":"chesterton_product","link":"https:\/\/aw-chesterton.eu\/fr\/products\/graisses\/617e\/","title":{"rendered":"617(E)"},"content":{"rendered":"<p>Graisse haute performance, prot\u00e9g\u00e9e contre la corrosion, avec d&#039;excellentes r\u00e9sistances aux pressions extr\u00eames et une excellente r\u00e9sistance au lavage \u00e0 l&#039;eau. Huile de base de Medium viscosity pour couvrir une large gamme d&#039;applications.<\/p>\n<h3 class=\"chesterton-section-heading\">Avantages<\/h3>\n<ul class=\"chesterton-product-advantages\">\n<li>Prolonge la dur\u00e9e de vie des paliers<\/li>\n<li>R\u00e9duit les temps d\u2019arr\u00eat<\/li>\n<li>Augmente la productivit\u00e9<\/li>\n<li>R\u00e9duit la consommation de graisse.<\/li>\n<\/ul>\n<h3 class=\"chesterton-section-heading\">Param\u00e8tres<\/h3>\n<table class=\"chesterton-product-data__table\">\n<tbody>\n<tr>\n<td>Caract\u00e9ristiques du produit<\/td>\n<td>Applications<\/td>\n<\/tr>\n<tr>\n<td>Excellente pour les pressions et les temp\u00e9ratures extr\u00eames<br \/>\nR\u00e9sistance sup\u00e9rieure au water lavage \u00e0 l&#039;eau<br \/>\nCompatible with most popular greases<br \/>\nR\u00e9sistance exceptionnelle au cisaillement <br \/>\nPr\u00e9vention du durcissement par des antioxydants<br \/>\nTemp\u00e9ratures limites : -30 \u00b0C \u00e0 204 \u00b0C (-22 \u00b0F \u00e0 400 \u00b0F)<\/td>\n<td>Bearings<br \/>\nTransporteurs<br \/>\nFraisage<br \/>\nPresses<br \/>\nSouffleurs<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">Conditionnements disponibles:<\/td>\n<\/tr>\n<tr>\n<td>400 g, 18 kg, 181 kg<\/td>\n<td><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Graisse haute performance, prot\u00e9g\u00e9e contre la corrosion, avec d&#039;excellentes r\u00e9sistances aux pressions extr\u00eames et une excellente r\u00e9sistance au lavage \u00e0 l&#039;eau. Huile de base de Medium viscosity pour couvrir une large gamme d&#039;applications. Avantages Prolonge la dur\u00e9e de vie des paliers R\u00e9duit les temps d\u2019arr\u00eat Augmente la productivit\u00e9 R\u00e9duit la consommation de graisse. Param\u00e8tres Caract\u00e9ristiques&hellip;<\/p>\n","protected":false},"featured_media":12481,"template":"","product_category":[13657],"class_list":["post-9522","chesterton_product","type-chesterton_product","status-publish","has-post-thumbnail","hentry","product_category-graisses"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>617(E) - A.W. Chesterton Company \u2013 EU<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aw-chesterton.eu\/fr\/products\/graisses\/617e\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"617(E) - A.W. Chesterton Company \u2013 EU\" \/>\n<meta property=\"og:description\" content=\"Graisse haute performance, prot\u00e9g\u00e9e contre la corrosion, avec d&#039;excellentes r\u00e9sistances aux pressions extr\u00eames et une excellente r\u00e9sistance au lavage \u00e0 l&#039;eau. Huile de base de Medium viscosity pour couvrir une large gamme d&#039;applications. Avantages Prolonge la dur\u00e9e de vie des paliers R\u00e9duit les temps d\u2019arr\u00eat Augmente la productivit\u00e9 R\u00e9duit la consommation de graisse. Param\u00e8tres Caract\u00e9ristiques&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aw-chesterton.eu\/fr\/products\/graisses\/617e\/\" \/>\n<meta property=\"og:site_name\" content=\"A.W. Chesterton Company \u2013 EU\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-02T10:30:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aw-chesterton.eu\/wp-content\/uploads\/2025\/01\/617e_hpg_400x345_b.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"345\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/fr\\\/products\\\/graisses\\\/617e\\\/\",\"url\":\"https:\\\/\\\/aw-chesterton.eu\\\/fr\\\/products\\\/graisses\\\/617e\\\/\",\"name\":\"617(E) - A.W. Chesterton Company \u2013 EU\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/fr\\\/products\\\/graisses\\\/617e\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/fr\\\/products\\\/graisses\\\/617e\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aw-chesterton.eu\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/617e_hpg_400x345_b.jpg\",\"datePublished\":\"2026-05-12T13:26:53+00:00\",\"dateModified\":\"2026-06-02T10:30:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/fr\\\/products\\\/graisses\\\/617e\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aw-chesterton.eu\\\/fr\\\/products\\\/graisses\\\/617e\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/fr\\\/products\\\/graisses\\\/617e\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aw-chesterton.eu\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/617e_hpg_400x345_b.jpg\",\"contentUrl\":\"https:\\\/\\\/aw-chesterton.eu\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/617e_hpg_400x345_b.jpg\",\"width\":400,\"height\":345},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/fr\\\/products\\\/graisses\\\/617e\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aw-chesterton.eu\\\/fr\\\/page-daccueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lubrifiants industriels et produits d\u2019entretien, de r\u00e9paration et de maintenance\",\"item\":\"https:\\\/\\\/aw-chesterton.eu\\\/fr\\\/products\\\/lubrifiants-industriels-et-produits-dentretien-de-reparation-et-de-maintenance\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Graisses\",\"item\":\"https:\\\/\\\/aw-chesterton.eu\\\/fr\\\/products\\\/graisses\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"617(E)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/aw-chesterton.eu\\\/fr\\\/\",\"name\":\"A.W. Chesterton Company \u2013 EU\",\"description\":\"A.W. Chesterton Company \u2013 EU\",\"publisher\":{\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aw-chesterton.eu\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/fr\\\/#organization\",\"name\":\"Chesterton Deutschland\",\"url\":\"https:\\\/\\\/aw-chesterton.eu\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aw-chesterton.eu\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Chesterton_Logo_CMYK_Vect.png\",\"contentUrl\":\"https:\\\/\\\/aw-chesterton.eu\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Chesterton_Logo_CMYK_Vect.png\",\"width\":1200,\"height\":218,\"caption\":\"Chesterton Deutschland\"},\"image\":{\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"617(E) - A.W. Chesterton Company \u2013 EU","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aw-chesterton.eu\/fr\/products\/graisses\/617e\/","og_locale":"fr_FR","og_type":"article","og_title":"617(E) - A.W. Chesterton Company \u2013 EU","og_description":"Graisse haute performance, prot\u00e9g\u00e9e contre la corrosion, avec d&#039;excellentes r\u00e9sistances aux pressions extr\u00eames et une excellente r\u00e9sistance au lavage \u00e0 l&#039;eau. Huile de base de Medium viscosity pour couvrir une large gamme d&#039;applications. Avantages Prolonge la dur\u00e9e de vie des paliers R\u00e9duit les temps d\u2019arr\u00eat Augmente la productivit\u00e9 R\u00e9duit la consommation de graisse. Param\u00e8tres Caract\u00e9ristiques&hellip;","og_url":"https:\/\/aw-chesterton.eu\/fr\/products\/graisses\/617e\/","og_site_name":"A.W. Chesterton Company \u2013 EU","article_modified_time":"2026-06-02T10:30:41+00:00","og_image":[{"width":400,"height":345,"url":"https:\/\/aw-chesterton.eu\/wp-content\/uploads\/2025\/01\/617e_hpg_400x345_b.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/aw-chesterton.eu\/fr\/products\/graisses\/617e\/","url":"https:\/\/aw-chesterton.eu\/fr\/products\/graisses\/617e\/","name":"617(E) - A.W. Chesterton Company \u2013 EU","isPartOf":{"@id":"https:\/\/aw-chesterton.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aw-chesterton.eu\/fr\/products\/graisses\/617e\/#primaryimage"},"image":{"@id":"https:\/\/aw-chesterton.eu\/fr\/products\/graisses\/617e\/#primaryimage"},"thumbnailUrl":"https:\/\/aw-chesterton.eu\/wp-content\/uploads\/2025\/01\/617e_hpg_400x345_b.jpg","datePublished":"2026-05-12T13:26:53+00:00","dateModified":"2026-06-02T10:30:41+00:00","breadcrumb":{"@id":"https:\/\/aw-chesterton.eu\/fr\/products\/graisses\/617e\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aw-chesterton.eu\/fr\/products\/graisses\/617e\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/aw-chesterton.eu\/fr\/products\/graisses\/617e\/#primaryimage","url":"https:\/\/aw-chesterton.eu\/wp-content\/uploads\/2025\/01\/617e_hpg_400x345_b.jpg","contentUrl":"https:\/\/aw-chesterton.eu\/wp-content\/uploads\/2025\/01\/617e_hpg_400x345_b.jpg","width":400,"height":345},{"@type":"BreadcrumbList","@id":"https:\/\/aw-chesterton.eu\/fr\/products\/graisses\/617e\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aw-chesterton.eu\/fr\/page-daccueil\/"},{"@type":"ListItem","position":2,"name":"Lubrifiants industriels et produits d\u2019entretien, de r\u00e9paration et de maintenance","item":"https:\/\/aw-chesterton.eu\/fr\/products\/lubrifiants-industriels-et-produits-dentretien-de-reparation-et-de-maintenance\/"},{"@type":"ListItem","position":3,"name":"Graisses","item":"https:\/\/aw-chesterton.eu\/fr\/products\/graisses\/"},{"@type":"ListItem","position":4,"name":"617(E)"}]},{"@type":"WebSite","@id":"https:\/\/aw-chesterton.eu\/fr\/#website","url":"https:\/\/aw-chesterton.eu\/fr\/","name":"A.W. Chesterton Company \u2013 EU","description":"A.W. Chesterton Company \u2013 EU","publisher":{"@id":"https:\/\/aw-chesterton.eu\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aw-chesterton.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/aw-chesterton.eu\/fr\/#organization","name":"Chesterton Deutschland","url":"https:\/\/aw-chesterton.eu\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/aw-chesterton.eu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/aw-chesterton.eu\/wp-content\/uploads\/2026\/03\/Chesterton_Logo_CMYK_Vect.png","contentUrl":"https:\/\/aw-chesterton.eu\/wp-content\/uploads\/2026\/03\/Chesterton_Logo_CMYK_Vect.png","width":1200,"height":218,"caption":"Chesterton Deutschland"},"image":{"@id":"https:\/\/aw-chesterton.eu\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/aw-chesterton.eu\/fr\/wp-json\/wp\/v2\/chesterton_product\/9522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aw-chesterton.eu\/fr\/wp-json\/wp\/v2\/chesterton_product"}],"about":[{"href":"https:\/\/aw-chesterton.eu\/fr\/wp-json\/wp\/v2\/types\/chesterton_product"}],"version-history":[{"count":3,"href":"https:\/\/aw-chesterton.eu\/fr\/wp-json\/wp\/v2\/chesterton_product\/9522\/revisions"}],"predecessor-version":[{"id":28142,"href":"https:\/\/aw-chesterton.eu\/fr\/wp-json\/wp\/v2\/chesterton_product\/9522\/revisions\/28142"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aw-chesterton.eu\/fr\/wp-json\/wp\/v2\/media\/12481"}],"wp:attachment":[{"href":"https:\/\/aw-chesterton.eu\/fr\/wp-json\/wp\/v2\/media?parent=9522"}],"wp:term":[{"taxonomy":"product_category","embeddable":true,"href":"https:\/\/aw-chesterton.eu\/fr\/wp-json\/wp\/v2\/product_category?post=9522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}