{"id":13658,"count":12,"description":"","link":"https:\/\/aw-chesterton.eu\/es\/products\/grasas\/","name":"Grasas","slug":"grasas","taxonomy":"product_category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Grasas Archive - A.W. Chesterton Company \u2013 EU<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aw-chesterton.eu\/es\/products\/grasas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Grasas Archive - A.W. Chesterton Company \u2013 EU\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aw-chesterton.eu\/es\/products\/grasas\/\" \/>\n<meta property=\"og:site_name\" content=\"A.W. Chesterton Company \u2013 EU\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/es\\\/products\\\/grasas\\\/\",\"url\":\"https:\\\/\\\/aw-chesterton.eu\\\/es\\\/products\\\/grasas\\\/\",\"name\":\"Grasas Archive - A.W. Chesterton Company \u2013 EU\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/es\\\/products\\\/grasas\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/es\\\/products\\\/grasas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aw-chesterton.eu\\\/es\\\/portada\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Grasas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/aw-chesterton.eu\\\/es\\\/\",\"name\":\"A.W. Chesterton Company \u2013 EU\",\"description\":\"A.W. Chesterton Company \u2013 EU\",\"publisher\":{\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aw-chesterton.eu\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/es\\\/#organization\",\"name\":\"Chesterton Deutschland\",\"url\":\"https:\\\/\\\/aw-chesterton.eu\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aw-chesterton.eu\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Chesterton_Logo_CMYK_Vect.png\",\"contentUrl\":\"https:\\\/\\\/aw-chesterton.eu\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Chesterton_Logo_CMYK_Vect.png\",\"width\":1200,\"height\":218,\"caption\":\"Chesterton Deutschland\"},\"image\":{\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Grasas Archive - A.W. Chesterton Company \u2013 EU","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aw-chesterton.eu\/es\/products\/grasas\/","og_locale":"es_ES","og_type":"article","og_title":"Grasas Archive - A.W. Chesterton Company \u2013 EU","og_url":"https:\/\/aw-chesterton.eu\/es\/products\/grasas\/","og_site_name":"A.W. Chesterton Company \u2013 EU","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/aw-chesterton.eu\/es\/products\/grasas\/","url":"https:\/\/aw-chesterton.eu\/es\/products\/grasas\/","name":"Grasas Archive - A.W. Chesterton Company \u2013 EU","isPartOf":{"@id":"https:\/\/aw-chesterton.eu\/es\/#website"},"breadcrumb":{"@id":"https:\/\/aw-chesterton.eu\/es\/products\/grasas\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/aw-chesterton.eu\/es\/products\/grasas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aw-chesterton.eu\/es\/portada\/"},{"@type":"ListItem","position":2,"name":"Grasas"}]},{"@type":"WebSite","@id":"https:\/\/aw-chesterton.eu\/es\/#website","url":"https:\/\/aw-chesterton.eu\/es\/","name":"A.W. Chesterton Company \u2013 EU","description":"A.W. Chesterton Company \u2013 EU","publisher":{"@id":"https:\/\/aw-chesterton.eu\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aw-chesterton.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/aw-chesterton.eu\/es\/#organization","name":"Chesterton Deutschland","url":"https:\/\/aw-chesterton.eu\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/aw-chesterton.eu\/es\/#\/schema\/logo\/image\/","url":"https:\/\/aw-chesterton.eu\/wp-content\/uploads\/2026\/03\/Chesterton_Logo_CMYK_Vect.png","contentUrl":"https:\/\/aw-chesterton.eu\/wp-content\/uploads\/2026\/03\/Chesterton_Logo_CMYK_Vect.png","width":1200,"height":218,"caption":"Chesterton Deutschland"},"image":{"@id":"https:\/\/aw-chesterton.eu\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/aw-chesterton.eu\/es\/wp-json\/wp\/v2\/product_category\/13658","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aw-chesterton.eu\/es\/wp-json\/wp\/v2\/product_category"}],"about":[{"href":"https:\/\/aw-chesterton.eu\/es\/wp-json\/wp\/v2\/taxonomies\/product_category"}],"wp:post_type":[{"href":"https:\/\/aw-chesterton.eu\/es\/wp-json\/wp\/v2\/chesterton_product?product_category=13658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}