{"id":10399,"date":"2026-05-12T13:44:49","date_gmt":"2026-05-12T13:44:49","guid":{"rendered":"https:\/\/aw-chesterton.eu\/products\/uncategorized\/972e\/"},"modified":"2026-05-12T13:51:27","modified_gmt":"2026-05-12T13:51:27","slug":"972e","status":"publish","type":"chesterton_product","link":"https:\/\/aw-chesterton.eu\/de\/products\/zirkulierende-kuhlschmierstoffe\/972e\/","title":{"rendered":"972(E)"},"content":{"rendered":"<p>Diese DEA- und borfreie Formulierung der neuen Generation beinhaltet alle Vorteile der<br \/>\nsynthetischen Technologie. \u00dcberlegene, nicht sch\u00e4umende Inhaltsstoffe, Korrosionsinhibitoren und Extremdruckadditive bieten eine erstklassige, vielseitig einsetzbare Metallbearbeitungsfl\u00fcssigkeit f\u00fcr hohe Geschwindigkeiten und Vorsch\u00fcbe.<\/p>\n<h3 class=\"chesterton-section-heading\">Vorteile<\/h3>\n<ul class=\"chesterton-product-advantages\">\n<li>DEA und borfreie Formulierung<\/li>\n<li>\u00d6lfrei \u2212 kein \u00d6lnebel<\/li>\n<li>Saubere Maschine und Teile<\/li>\n<li>Hohe Oberfl\u00e4chengeschwindigkeit \u2212 erh\u00f6hte Produktivit\u00e4t<\/li>\n<\/ul>\n<h3 class=\"chesterton-section-heading\">Eigenschaften<\/h3>\n<table class=\"chesterton-product-data__table\">\n<tbody>\n<tr>\n<td>Produkteigenschaften<\/td>\n<td>Anwendungen<\/td>\n<\/tr>\n<tr>\n<td>\u00dcberlegene K\u00fchleigenschaften<br \/>\nSepariert Fremd\u00f6l<br \/>\nHervorragende Sp\u00e4neabsetzung und Filtrierbarkeit<br \/>\nReduziert die Hitze bei hohen Geschwindigkeiten und Vorsch\u00fcben<br \/>\nReduziert starke Ger\u00fcche, die bei Emulsionen zu erwarten sind<br \/>\nKeine klebrigen R\u00fcckst\u00e4nde<br \/>\nBioresistente Zusammensetzung reduziert mikrobiellen Befall<br \/>\nErm\u00f6glicht ein sauberes, sicheres Arbeitsumfeld<\/td>\n<td>R\u00e4umen, S\u00e4gen, Reiben, Tiefziehen<br \/>\nGewindebohren, Gewindeschneiden, Bohren<br \/>\nDrehen, Schleifen, Stanzen<\/td>\n<\/tr>\n<tr>\n<td>Erh\u00e4ltliche Beh\u00e4ltergr\u00f6\u00dfen: 20 l, 208 l, 1 000 l<\/td>\n<td><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Opticool Emulsion, Vollsynthetisch<\/p>\n","protected":false},"featured_media":10579,"template":"","product_category":[13725],"class_list":["post-10399","chesterton_product","type-chesterton_product","status-publish","has-post-thumbnail","hentry","product_category-zirkulierende-kuhlschmierstoffe"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>972(E) - A.W. Chesterton Company \u2013 EU<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aw-chesterton.eu\/de\/products\/zirkulierende-kuhlschmierstoffe\/972e\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"972(E) - A.W. Chesterton Company \u2013 EU\" \/>\n<meta property=\"og:description\" content=\"Opticool Emulsion, Vollsynthetisch\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aw-chesterton.eu\/de\/products\/zirkulierende-kuhlschmierstoffe\/972e\/\" \/>\n<meta property=\"og:site_name\" content=\"A.W. Chesterton Company \u2013 EU\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T13:51:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aw-chesterton.eu\/wp-content\/uploads\/2025\/01\/opticool_972_e_20_ltrs_11_2018.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"939\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/products\\\/zirkulierende-kuhlschmierstoffe\\\/972e\\\/\",\"url\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/products\\\/zirkulierende-kuhlschmierstoffe\\\/972e\\\/\",\"name\":\"972(E) - A.W. Chesterton Company \u2013 EU\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/products\\\/zirkulierende-kuhlschmierstoffe\\\/972e\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/products\\\/zirkulierende-kuhlschmierstoffe\\\/972e\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aw-chesterton.eu\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/opticool_972_e_20_ltrs_11_2018.jpg\",\"datePublished\":\"2026-05-12T13:44:49+00:00\",\"dateModified\":\"2026-05-12T13:51:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/products\\\/zirkulierende-kuhlschmierstoffe\\\/972e\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/products\\\/zirkulierende-kuhlschmierstoffe\\\/972e\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/products\\\/zirkulierende-kuhlschmierstoffe\\\/972e\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aw-chesterton.eu\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/opticool_972_e_20_ltrs_11_2018.jpg\",\"contentUrl\":\"https:\\\/\\\/aw-chesterton.eu\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/opticool_972_e_20_ltrs_11_2018.jpg\",\"width\":939,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/products\\\/zirkulierende-kuhlschmierstoffe\\\/972e\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Industrielle Schmierstoffe und chemisch-technische Wartungsprodukte\",\"item\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/products\\\/industrielle-schmierstoffe-und-chemisch-technische-wartungsprodukte\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Metallbearbeitungsfl\u00fcssigkeiten\",\"item\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/products\\\/metallbearbeitungsflussigkeiten\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Zirkulierende K\u00fchlschmierstoffe\",\"item\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/products\\\/zirkulierende-kuhlschmierstoffe\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"972(E)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/\",\"name\":\"A.W. Chesterton Company \u2013 EU\",\"description\":\"A.W. Chesterton Company \u2013 EU\",\"publisher\":{\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/#organization\",\"name\":\"Chesterton Deutschland\",\"url\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aw-chesterton.eu\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Chesterton_Logo_CMYK_Vect.png\",\"contentUrl\":\"https:\\\/\\\/aw-chesterton.eu\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Chesterton_Logo_CMYK_Vect.png\",\"width\":1200,\"height\":218,\"caption\":\"Chesterton Deutschland\"},\"image\":{\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"972(E) - A.W. Chesterton Company \u2013 EU","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aw-chesterton.eu\/de\/products\/zirkulierende-kuhlschmierstoffe\/972e\/","og_locale":"de_DE","og_type":"article","og_title":"972(E) - A.W. Chesterton Company \u2013 EU","og_description":"Opticool Emulsion, Vollsynthetisch","og_url":"https:\/\/aw-chesterton.eu\/de\/products\/zirkulierende-kuhlschmierstoffe\/972e\/","og_site_name":"A.W. Chesterton Company \u2013 EU","article_modified_time":"2026-05-12T13:51:27+00:00","og_image":[{"width":939,"height":1024,"url":"https:\/\/aw-chesterton.eu\/wp-content\/uploads\/2025\/01\/opticool_972_e_20_ltrs_11_2018.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/aw-chesterton.eu\/de\/products\/zirkulierende-kuhlschmierstoffe\/972e\/","url":"https:\/\/aw-chesterton.eu\/de\/products\/zirkulierende-kuhlschmierstoffe\/972e\/","name":"972(E) - A.W. Chesterton Company \u2013 EU","isPartOf":{"@id":"https:\/\/aw-chesterton.eu\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aw-chesterton.eu\/de\/products\/zirkulierende-kuhlschmierstoffe\/972e\/#primaryimage"},"image":{"@id":"https:\/\/aw-chesterton.eu\/de\/products\/zirkulierende-kuhlschmierstoffe\/972e\/#primaryimage"},"thumbnailUrl":"https:\/\/aw-chesterton.eu\/wp-content\/uploads\/2025\/01\/opticool_972_e_20_ltrs_11_2018.jpg","datePublished":"2026-05-12T13:44:49+00:00","dateModified":"2026-05-12T13:51:27+00:00","breadcrumb":{"@id":"https:\/\/aw-chesterton.eu\/de\/products\/zirkulierende-kuhlschmierstoffe\/972e\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aw-chesterton.eu\/de\/products\/zirkulierende-kuhlschmierstoffe\/972e\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/aw-chesterton.eu\/de\/products\/zirkulierende-kuhlschmierstoffe\/972e\/#primaryimage","url":"https:\/\/aw-chesterton.eu\/wp-content\/uploads\/2025\/01\/opticool_972_e_20_ltrs_11_2018.jpg","contentUrl":"https:\/\/aw-chesterton.eu\/wp-content\/uploads\/2025\/01\/opticool_972_e_20_ltrs_11_2018.jpg","width":939,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/aw-chesterton.eu\/de\/products\/zirkulierende-kuhlschmierstoffe\/972e\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aw-chesterton.eu\/de\/"},{"@type":"ListItem","position":2,"name":"Industrielle Schmierstoffe und chemisch-technische Wartungsprodukte","item":"https:\/\/aw-chesterton.eu\/de\/products\/industrielle-schmierstoffe-und-chemisch-technische-wartungsprodukte\/"},{"@type":"ListItem","position":3,"name":"Metallbearbeitungsfl\u00fcssigkeiten","item":"https:\/\/aw-chesterton.eu\/de\/products\/metallbearbeitungsflussigkeiten\/"},{"@type":"ListItem","position":4,"name":"Zirkulierende K\u00fchlschmierstoffe","item":"https:\/\/aw-chesterton.eu\/de\/products\/zirkulierende-kuhlschmierstoffe\/"},{"@type":"ListItem","position":5,"name":"972(E)"}]},{"@type":"WebSite","@id":"https:\/\/aw-chesterton.eu\/de\/#website","url":"https:\/\/aw-chesterton.eu\/de\/","name":"A.W. Chesterton Company \u2013 EU","description":"A.W. Chesterton Company \u2013 EU","publisher":{"@id":"https:\/\/aw-chesterton.eu\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aw-chesterton.eu\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/aw-chesterton.eu\/de\/#organization","name":"Chesterton Deutschland","url":"https:\/\/aw-chesterton.eu\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/aw-chesterton.eu\/de\/#\/schema\/logo\/image\/","url":"https:\/\/aw-chesterton.eu\/wp-content\/uploads\/2026\/03\/Chesterton_Logo_CMYK_Vect.png","contentUrl":"https:\/\/aw-chesterton.eu\/wp-content\/uploads\/2026\/03\/Chesterton_Logo_CMYK_Vect.png","width":1200,"height":218,"caption":"Chesterton Deutschland"},"image":{"@id":"https:\/\/aw-chesterton.eu\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/aw-chesterton.eu\/de\/wp-json\/wp\/v2\/chesterton_product\/10399","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aw-chesterton.eu\/de\/wp-json\/wp\/v2\/chesterton_product"}],"about":[{"href":"https:\/\/aw-chesterton.eu\/de\/wp-json\/wp\/v2\/types\/chesterton_product"}],"version-history":[{"count":1,"href":"https:\/\/aw-chesterton.eu\/de\/wp-json\/wp\/v2\/chesterton_product\/10399\/revisions"}],"predecessor-version":[{"id":10580,"href":"https:\/\/aw-chesterton.eu\/de\/wp-json\/wp\/v2\/chesterton_product\/10399\/revisions\/10580"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aw-chesterton.eu\/de\/wp-json\/wp\/v2\/media\/10579"}],"wp:attachment":[{"href":"https:\/\/aw-chesterton.eu\/de\/wp-json\/wp\/v2\/media?parent=10399"}],"wp:term":[{"taxonomy":"product_category","embeddable":true,"href":"https:\/\/aw-chesterton.eu\/de\/wp-json\/wp\/v2\/product_category?post=10399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}