{"id":10355,"date":"2026-05-12T13:44:48","date_gmt":"2026-05-12T13:44:48","guid":{"rendered":"https:\/\/aw-chesterton.eu\/products\/uncategorized\/785e-und-785-fg\/"},"modified":"2026-06-02T12:30:56","modified_gmt":"2026-06-02T10:30:56","slug":"785e-und-785-fg","status":"publish","type":"chesterton_product","link":"https:\/\/aw-chesterton.eu\/de\/products\/fett-schmierfett\/785e-und-785-fg\/","title":{"rendered":"785(E) und 785 FG"},"content":{"rendered":"<p>Diese neue Generation eines Anti-Haftmittels enth\u00e4lt eine Mischung aus extrem feinen, anorganischen Schmierstoffen in einem nicht verkokenden, aschelosen synthetischen Tr\u00e4ger. Es h\u00e4lt extrem hoher Temperatur und extremem Druck stand.<\/p>\n<h3 class=\"chesterton-section-heading\">Vorteile<\/h3>\n<ul class=\"chesterton-product-advantages\">\n<li>Schmierstoff f\u00fcr Montage\/Demontage<\/li>\n<li>Schutz gegen Korrosion<\/li>\n<li>Keine Drehmoment-Nachberechnungen erforderlich<\/li>\n<\/ul>\n<h3 class=\"chesterton-section-heading\">Eigenschaften<\/h3>\n<table class=\"chesterton-product-data__table\">\n<tbody>\n<tr>\n<td>Produkteigenschaften<\/td>\n<td>Anwendungen<\/td>\n<\/tr>\n<tr>\n<td>Erleichtert die Demontage bis zu 1 204 \u00b0C (2 200 \u00b0F)<\/td>\n<td>Alle Industriesparten<\/td>\n<\/tr>\n<tr>\n<td>F\u00fcllt mikroskopisch kleine Leerstellen <br \/>\nKeine toxischen Schwermetalle <br \/>\nF\u00fcr extremen Druck bis zu 4 730 kg\/cm2 (67 570 psi)<\/td>\n<td>Bolzen <br \/>\nSchrauben <br \/>\nZapfen <br \/>\nRohrgewinde <br \/>\nPresspassungen <br \/>\nPumpenh\u00fclsen<\/td>\n<\/tr>\n<tr>\n<td>Erh\u00e4ltliche Beh\u00e4ltergr\u00f6\u00dfen:<\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">&gt; 785: 200 g, 250 g, 500 g, Spr\u00fchdose, 20 l<br \/>\n&gt; 785FG: 200 g, 500 g<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">Hinweis: FG bedeutet, dass dieses Produkt f\u00fcr den Einsatz in der Lebensmittelindustrie geeignet ist.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Trenn-\/Schmierstoff <\/p>\n","protected":false},"featured_media":10648,"template":"","product_category":[13661,13666],"class_list":["post-10355","chesterton_product","type-chesterton_product","status-publish","has-post-thumbnail","hentry","product_category-fett-schmierfett","product_category-kontakt-mit-nahrungsmitteln"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>785(E) und 785 FG - A.W. Chesterton Company \u2013 EU<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aw-chesterton.eu\/de\/products\/fett-schmierfett\/785e-und-785-fg\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"785(E) und 785 FG - A.W. Chesterton Company \u2013 EU\" \/>\n<meta property=\"og:description\" content=\"Trenn-\/Schmierstoff\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aw-chesterton.eu\/de\/products\/fett-schmierfett\/785e-und-785-fg\/\" \/>\n<meta property=\"og:site_name\" content=\"A.W. Chesterton Company \u2013 EU\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-02T10:30:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aw-chesterton.eu\/wp-content\/uploads\/2025\/01\/785_785fg_photo_926.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"795\" \/>\n\t<meta property=\"og:image:height\" content=\"926\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/products\\\/fett-schmierfett\\\/785e-und-785-fg\\\/\",\"url\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/products\\\/fett-schmierfett\\\/785e-und-785-fg\\\/\",\"name\":\"785(E) und 785 FG - A.W. Chesterton Company \u2013 EU\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/products\\\/fett-schmierfett\\\/785e-und-785-fg\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/products\\\/fett-schmierfett\\\/785e-und-785-fg\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aw-chesterton.eu\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/785_785fg_photo_926.jpg\",\"datePublished\":\"2026-05-12T13:44:48+00:00\",\"dateModified\":\"2026-06-02T10:30:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/products\\\/fett-schmierfett\\\/785e-und-785-fg\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/products\\\/fett-schmierfett\\\/785e-und-785-fg\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/products\\\/fett-schmierfett\\\/785e-und-785-fg\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aw-chesterton.eu\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/785_785fg_photo_926.jpg\",\"contentUrl\":\"https:\\\/\\\/aw-chesterton.eu\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/785_785fg_photo_926.jpg\",\"width\":795,\"height\":926},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/products\\\/fett-schmierfett\\\/785e-und-785-fg\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Industrielle Schmierstoffe und chemisch-technische Wartungsprodukte\",\"item\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/products\\\/industrielle-schmierstoffe-und-chemisch-technische-wartungsprodukte\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Fett\\\/Schmierfett\",\"item\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/products\\\/fett-schmierfett\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"785(E) und 785 FG\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/\",\"name\":\"A.W. Chesterton Company \u2013 EU\",\"description\":\"A.W. Chesterton Company \u2013 EU\",\"publisher\":{\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/#organization\",\"name\":\"Chesterton Deutschland\",\"url\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aw-chesterton.eu\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Chesterton_Logo_CMYK_Vect.png\",\"contentUrl\":\"https:\\\/\\\/aw-chesterton.eu\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Chesterton_Logo_CMYK_Vect.png\",\"width\":1200,\"height\":218,\"caption\":\"Chesterton Deutschland\"},\"image\":{\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"785(E) und 785 FG - A.W. Chesterton Company \u2013 EU","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aw-chesterton.eu\/de\/products\/fett-schmierfett\/785e-und-785-fg\/","og_locale":"de_DE","og_type":"article","og_title":"785(E) und 785 FG - A.W. Chesterton Company \u2013 EU","og_description":"Trenn-\/Schmierstoff","og_url":"https:\/\/aw-chesterton.eu\/de\/products\/fett-schmierfett\/785e-und-785-fg\/","og_site_name":"A.W. Chesterton Company \u2013 EU","article_modified_time":"2026-06-02T10:30:56+00:00","og_image":[{"width":795,"height":926,"url":"https:\/\/aw-chesterton.eu\/wp-content\/uploads\/2025\/01\/785_785fg_photo_926.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/aw-chesterton.eu\/de\/products\/fett-schmierfett\/785e-und-785-fg\/","url":"https:\/\/aw-chesterton.eu\/de\/products\/fett-schmierfett\/785e-und-785-fg\/","name":"785(E) und 785 FG - A.W. Chesterton Company \u2013 EU","isPartOf":{"@id":"https:\/\/aw-chesterton.eu\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aw-chesterton.eu\/de\/products\/fett-schmierfett\/785e-und-785-fg\/#primaryimage"},"image":{"@id":"https:\/\/aw-chesterton.eu\/de\/products\/fett-schmierfett\/785e-und-785-fg\/#primaryimage"},"thumbnailUrl":"https:\/\/aw-chesterton.eu\/wp-content\/uploads\/2025\/01\/785_785fg_photo_926.jpg","datePublished":"2026-05-12T13:44:48+00:00","dateModified":"2026-06-02T10:30:56+00:00","breadcrumb":{"@id":"https:\/\/aw-chesterton.eu\/de\/products\/fett-schmierfett\/785e-und-785-fg\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aw-chesterton.eu\/de\/products\/fett-schmierfett\/785e-und-785-fg\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/aw-chesterton.eu\/de\/products\/fett-schmierfett\/785e-und-785-fg\/#primaryimage","url":"https:\/\/aw-chesterton.eu\/wp-content\/uploads\/2025\/01\/785_785fg_photo_926.jpg","contentUrl":"https:\/\/aw-chesterton.eu\/wp-content\/uploads\/2025\/01\/785_785fg_photo_926.jpg","width":795,"height":926},{"@type":"BreadcrumbList","@id":"https:\/\/aw-chesterton.eu\/de\/products\/fett-schmierfett\/785e-und-785-fg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aw-chesterton.eu\/de\/"},{"@type":"ListItem","position":2,"name":"Industrielle Schmierstoffe und chemisch-technische Wartungsprodukte","item":"https:\/\/aw-chesterton.eu\/de\/products\/industrielle-schmierstoffe-und-chemisch-technische-wartungsprodukte\/"},{"@type":"ListItem","position":3,"name":"Fett\/Schmierfett","item":"https:\/\/aw-chesterton.eu\/de\/products\/fett-schmierfett\/"},{"@type":"ListItem","position":4,"name":"785(E) und 785 FG"}]},{"@type":"WebSite","@id":"https:\/\/aw-chesterton.eu\/de\/#website","url":"https:\/\/aw-chesterton.eu\/de\/","name":"A.W. Chesterton Company \u2013 EU","description":"A.W. Chesterton Company \u2013 EU","publisher":{"@id":"https:\/\/aw-chesterton.eu\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aw-chesterton.eu\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/aw-chesterton.eu\/de\/#organization","name":"Chesterton Deutschland","url":"https:\/\/aw-chesterton.eu\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/aw-chesterton.eu\/de\/#\/schema\/logo\/image\/","url":"https:\/\/aw-chesterton.eu\/wp-content\/uploads\/2026\/03\/Chesterton_Logo_CMYK_Vect.png","contentUrl":"https:\/\/aw-chesterton.eu\/wp-content\/uploads\/2026\/03\/Chesterton_Logo_CMYK_Vect.png","width":1200,"height":218,"caption":"Chesterton Deutschland"},"image":{"@id":"https:\/\/aw-chesterton.eu\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/aw-chesterton.eu\/de\/wp-json\/wp\/v2\/chesterton_product\/10355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aw-chesterton.eu\/de\/wp-json\/wp\/v2\/chesterton_product"}],"about":[{"href":"https:\/\/aw-chesterton.eu\/de\/wp-json\/wp\/v2\/types\/chesterton_product"}],"version-history":[{"count":2,"href":"https:\/\/aw-chesterton.eu\/de\/wp-json\/wp\/v2\/chesterton_product\/10355\/revisions"}],"predecessor-version":[{"id":28263,"href":"https:\/\/aw-chesterton.eu\/de\/wp-json\/wp\/v2\/chesterton_product\/10355\/revisions\/28263"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aw-chesterton.eu\/de\/wp-json\/wp\/v2\/media\/10648"}],"wp:attachment":[{"href":"https:\/\/aw-chesterton.eu\/de\/wp-json\/wp\/v2\/media?parent=10355"}],"wp:term":[{"taxonomy":"product_category","embeddable":true,"href":"https:\/\/aw-chesterton.eu\/de\/wp-json\/wp\/v2\/product_category?post=10355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}