{"id":10259,"date":"2026-05-12T13:44:44","date_gmt":"2026-05-12T13:44:44","guid":{"rendered":"https:\/\/aw-chesterton.eu\/products\/uncategorized\/r22k\/"},"modified":"2026-06-02T12:31:53","modified_gmt":"2026-06-02T10:31:53","slug":"r22k","status":"publish","type":"chesterton_product","link":"https:\/\/aw-chesterton.eu\/de\/products\/nutringkonstruktion\/r22k\/","title":{"rendered":"R22K"},"content":{"rendered":"<p>Flexible Produktserie von Hochleistungs-Hydraulikdichtungen f\u00fcr Standard- und Hochdruckanwendungen.<\/p>\n<h3 class=\"chesterton-section-heading\">Vorteile<\/h3>\n<ul class=\"chesterton-product-advantages\">\n<li>Einfach wirkendes Nutring Design mit Null Leckage \u00fcber den gesamten Betriebsbereich<\/li>\n<li>Abriebbest\u00e4ndiges Design, ausgezeichnete Leistung in Hydraulikanwendungen<\/li>\n<li>Lippengeometrie stabilisiert die Dichtung, verhindert Verdrehen und vereinfacht den Einbau<\/li>\n<li>Anwendungsspezifische L\u00f6sungen, einschlie\u00dflich Anti-Extrusionring, Vorspannring und dynamische statische Lippendesigns<\/li>\n<\/ul>\n<h3 class=\"chesterton-section-heading\">Eigenschaften<\/h3>\n<table class=\"chesterton-product-data__table\">\n<tbody>\n<tr>\n<td>Werkstoff (Bezeichnung)<\/td>\n<td>Gr\u00f6\u00dfenbereich* mm (Zoll)<\/td>\n<td>Temperatur \u02daC (\u02daF)<\/td>\n<td>Druck MPa (psi)<\/td>\n<td>Geschwindigkeit ms-1 (ft\/min)<\/td>\n<\/tr>\n<tr>\n<td>AWC704 (FKM)<\/td>\n<td>6 \u2500 304.8 (1\/4 \u2500 12)<\/td>\n<td>-30  \u2500 200 (-20  \u2500 400)<\/td>\n<td>34.5 (5000)<\/td>\n<td>1.5 (300)<\/td>\n<\/tr>\n<tr class=\"is-alt\">\n<td>AWC800 (EU)<\/td>\n<td>6  \u2500 2540 (1\/4  \u2500 100)<\/td>\n<td>-50  \u2500 85 (-60  \u2500 185)<\/td>\n<td>103.5 (15000)<\/td>\n<td>1 (200)<\/td>\n<\/tr>\n<tr>\n<td>AWC825 (EU)<\/td>\n<td>6 \u2500 2540 (1\/4 \u2500 100)<\/td>\n<td>-40 \u2500 85 (-40 \u2500 185)<\/td>\n<td>52 (7500)<\/td>\n<td>0,5 (100)<\/td>\n<\/tr>\n<tr class=\"is-alt\">\n<td>AWC830 (EU)<\/td>\n<td>6 \u2500 254 (1\/4 \u2500 10)<\/td>\n<td>-35 \u2500 75 (-30 \u2500 165)<\/td>\n<td>52 (7500)<\/td>\n<td>0.9 (185)<\/td>\n<\/tr>\n<tr>\n<td>AWC860 (EU)<\/td>\n<td>6 \u2500 508 (1\/4 \u2500 20)<\/td>\n<td>-50  \u2500 120 (-60  \u2500 250)<\/td>\n<td>103.5 (15000)<\/td>\n<td>1.25 (250)<\/td>\n<\/tr>\n<tr>\n<td colspan=\"5\">Zutreffende Normen: DIN\/ISO 5597, DIN\/ISO 5597-1, DIN\/ISO 7425-2<\/td>\n<\/tr>\n<tr>\n<td colspan=\"5\">*Wenden Sie sich bitte an Ihren Chesterton-Vertreter f\u00fcr gr\u00f6\u00dfere Abmessungen<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Einfachwirkende Stangendichtung f\u00fcr Anwendungen in der Hydraulik<\/p>\n","protected":false},"featured_media":11478,"template":"","product_category":[13596],"class_list":["post-10259","chesterton_product","type-chesterton_product","status-publish","has-post-thumbnail","hentry","product_category-nutringkonstruktion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>R22K - A.W. Chesterton Company \u2013 EU<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aw-chesterton.eu\/de\/products\/nutringkonstruktion\/r22k\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R22K - A.W. Chesterton Company \u2013 EU\" \/>\n<meta property=\"og:description\" content=\"Einfachwirkende Stangendichtung f\u00fcr Anwendungen in der Hydraulik\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aw-chesterton.eu\/de\/products\/nutringkonstruktion\/r22k\/\" \/>\n<meta property=\"og:site_name\" content=\"A.W. Chesterton Company \u2013 EU\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-02T10:31:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aw-chesterton.eu\/wp-content\/uploads\/2025\/01\/r22k_photo_790.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"790\" \/>\n\t<meta property=\"og:image:height\" content=\"571\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/products\\\/nutringkonstruktion\\\/r22k\\\/\",\"url\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/products\\\/nutringkonstruktion\\\/r22k\\\/\",\"name\":\"R22K - A.W. Chesterton Company \u2013 EU\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/products\\\/nutringkonstruktion\\\/r22k\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/products\\\/nutringkonstruktion\\\/r22k\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aw-chesterton.eu\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/r22k_photo_790.jpg\",\"datePublished\":\"2026-05-12T13:44:44+00:00\",\"dateModified\":\"2026-06-02T10:31:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/products\\\/nutringkonstruktion\\\/r22k\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/products\\\/nutringkonstruktion\\\/r22k\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/products\\\/nutringkonstruktion\\\/r22k\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aw-chesterton.eu\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/r22k_photo_790.jpg\",\"contentUrl\":\"https:\\\/\\\/aw-chesterton.eu\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/r22k_photo_790.jpg\",\"width\":790,\"height\":571},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/products\\\/nutringkonstruktion\\\/r22k\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Polymer-Dichtungen\",\"item\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/products\\\/polymer-dichtungen\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Kolbendichtungen\",\"item\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/products\\\/kolbendichtungen\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Nutringkonstruktion\",\"item\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/products\\\/nutringkonstruktion\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"R22K\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/\",\"name\":\"A.W. Chesterton Company \u2013 EU\",\"description\":\"A.W. Chesterton Company \u2013 EU\",\"publisher\":{\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/#organization\",\"name\":\"Chesterton Deutschland\",\"url\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aw-chesterton.eu\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Chesterton_Logo_CMYK_Vect.png\",\"contentUrl\":\"https:\\\/\\\/aw-chesterton.eu\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Chesterton_Logo_CMYK_Vect.png\",\"width\":1200,\"height\":218,\"caption\":\"Chesterton Deutschland\"},\"image\":{\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R22K - A.W. Chesterton Company \u2013 EU","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aw-chesterton.eu\/de\/products\/nutringkonstruktion\/r22k\/","og_locale":"de_DE","og_type":"article","og_title":"R22K - A.W. Chesterton Company \u2013 EU","og_description":"Einfachwirkende Stangendichtung f\u00fcr Anwendungen in der Hydraulik","og_url":"https:\/\/aw-chesterton.eu\/de\/products\/nutringkonstruktion\/r22k\/","og_site_name":"A.W. Chesterton Company \u2013 EU","article_modified_time":"2026-06-02T10:31:53+00:00","og_image":[{"width":790,"height":571,"url":"https:\/\/aw-chesterton.eu\/wp-content\/uploads\/2025\/01\/r22k_photo_790.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/aw-chesterton.eu\/de\/products\/nutringkonstruktion\/r22k\/","url":"https:\/\/aw-chesterton.eu\/de\/products\/nutringkonstruktion\/r22k\/","name":"R22K - A.W. Chesterton Company \u2013 EU","isPartOf":{"@id":"https:\/\/aw-chesterton.eu\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aw-chesterton.eu\/de\/products\/nutringkonstruktion\/r22k\/#primaryimage"},"image":{"@id":"https:\/\/aw-chesterton.eu\/de\/products\/nutringkonstruktion\/r22k\/#primaryimage"},"thumbnailUrl":"https:\/\/aw-chesterton.eu\/wp-content\/uploads\/2025\/01\/r22k_photo_790.jpg","datePublished":"2026-05-12T13:44:44+00:00","dateModified":"2026-06-02T10:31:53+00:00","breadcrumb":{"@id":"https:\/\/aw-chesterton.eu\/de\/products\/nutringkonstruktion\/r22k\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aw-chesterton.eu\/de\/products\/nutringkonstruktion\/r22k\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/aw-chesterton.eu\/de\/products\/nutringkonstruktion\/r22k\/#primaryimage","url":"https:\/\/aw-chesterton.eu\/wp-content\/uploads\/2025\/01\/r22k_photo_790.jpg","contentUrl":"https:\/\/aw-chesterton.eu\/wp-content\/uploads\/2025\/01\/r22k_photo_790.jpg","width":790,"height":571},{"@type":"BreadcrumbList","@id":"https:\/\/aw-chesterton.eu\/de\/products\/nutringkonstruktion\/r22k\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aw-chesterton.eu\/de\/"},{"@type":"ListItem","position":2,"name":"Polymer-Dichtungen","item":"https:\/\/aw-chesterton.eu\/de\/products\/polymer-dichtungen\/"},{"@type":"ListItem","position":3,"name":"Kolbendichtungen","item":"https:\/\/aw-chesterton.eu\/de\/products\/kolbendichtungen\/"},{"@type":"ListItem","position":4,"name":"Nutringkonstruktion","item":"https:\/\/aw-chesterton.eu\/de\/products\/nutringkonstruktion\/"},{"@type":"ListItem","position":5,"name":"R22K"}]},{"@type":"WebSite","@id":"https:\/\/aw-chesterton.eu\/de\/#website","url":"https:\/\/aw-chesterton.eu\/de\/","name":"A.W. Chesterton Company \u2013 EU","description":"A.W. Chesterton Company \u2013 EU","publisher":{"@id":"https:\/\/aw-chesterton.eu\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aw-chesterton.eu\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/aw-chesterton.eu\/de\/#organization","name":"Chesterton Deutschland","url":"https:\/\/aw-chesterton.eu\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/aw-chesterton.eu\/de\/#\/schema\/logo\/image\/","url":"https:\/\/aw-chesterton.eu\/wp-content\/uploads\/2026\/03\/Chesterton_Logo_CMYK_Vect.png","contentUrl":"https:\/\/aw-chesterton.eu\/wp-content\/uploads\/2026\/03\/Chesterton_Logo_CMYK_Vect.png","width":1200,"height":218,"caption":"Chesterton Deutschland"},"image":{"@id":"https:\/\/aw-chesterton.eu\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/aw-chesterton.eu\/de\/wp-json\/wp\/v2\/chesterton_product\/10259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aw-chesterton.eu\/de\/wp-json\/wp\/v2\/chesterton_product"}],"about":[{"href":"https:\/\/aw-chesterton.eu\/de\/wp-json\/wp\/v2\/types\/chesterton_product"}],"version-history":[{"count":2,"href":"https:\/\/aw-chesterton.eu\/de\/wp-json\/wp\/v2\/chesterton_product\/10259\/revisions"}],"predecessor-version":[{"id":28683,"href":"https:\/\/aw-chesterton.eu\/de\/wp-json\/wp\/v2\/chesterton_product\/10259\/revisions\/28683"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aw-chesterton.eu\/de\/wp-json\/wp\/v2\/media\/11478"}],"wp:attachment":[{"href":"https:\/\/aw-chesterton.eu\/de\/wp-json\/wp\/v2\/media?parent=10259"}],"wp:term":[{"taxonomy":"product_category","embeddable":true,"href":"https:\/\/aw-chesterton.eu\/de\/wp-json\/wp\/v2\/product_category?post=10259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}