{"id":14093,"count":0,"description":"","link":"https:\/\/aw-chesterton.eu\/cs\/products\/dynamicka-regulace-zatizeni\/","name":"Dynamick\u00e1 regulace zat\u00ed\u017een\u00ed","slug":"dynamicka-regulace-zatizeni","taxonomy":"product_category","parent":14028,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dynamick\u00e1 regulace zat\u00ed\u017een\u00ed Archive - A.W. Chesterton Company \u2013 EU<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aw-chesterton.eu\/cs\/products\/dynamicka-regulace-zatizeni\/\" \/>\n<meta property=\"og:locale\" content=\"cs_CZ\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dynamick\u00e1 regulace zat\u00ed\u017een\u00ed Archive - A.W. Chesterton Company \u2013 EU\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aw-chesterton.eu\/cs\/products\/dynamicka-regulace-zatizeni\/\" \/>\n<meta property=\"og:site_name\" content=\"A.W. Chesterton Company \u2013 EU\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/cs\\\/products\\\/dynamicka-regulace-zatizeni\\\/\",\"url\":\"https:\\\/\\\/aw-chesterton.eu\\\/cs\\\/products\\\/dynamicka-regulace-zatizeni\\\/\",\"name\":\"Dynamick\u00e1 regulace zat\u00ed\u017een\u00ed Archive - A.W. Chesterton Company \u2013 EU\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/cs\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/cs\\\/products\\\/dynamicka-regulace-zatizeni\\\/#breadcrumb\"},\"inLanguage\":\"cs\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/cs\\\/products\\\/dynamicka-regulace-zatizeni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aw-chesterton.eu\\\/cs\\\/titulni-strana\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u011bkk\u00e9 ucp\u00e1vky a ploch\u00e1 t\u011bsn\u011bn\u00ed\",\"item\":\"https:\\\/\\\/aw-chesterton.eu\\\/cs\\\/products\\\/mekke-ucpavky-a-plocha-tesneni\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dynamick\u00e1 regulace zat\u00ed\u017een\u00ed\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/cs\\\/#website\",\"url\":\"https:\\\/\\\/aw-chesterton.eu\\\/cs\\\/\",\"name\":\"A.W. Chesterton Company \u2013 EU\",\"description\":\"A.W. Chesterton Company \u2013 EU\",\"publisher\":{\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/cs\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aw-chesterton.eu\\\/cs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"cs\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/cs\\\/#organization\",\"name\":\"Chesterton Deutschland\",\"url\":\"https:\\\/\\\/aw-chesterton.eu\\\/cs\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"cs\",\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/cs\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aw-chesterton.eu\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Chesterton_Logo_CMYK_Vect.png\",\"contentUrl\":\"https:\\\/\\\/aw-chesterton.eu\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Chesterton_Logo_CMYK_Vect.png\",\"width\":1200,\"height\":218,\"caption\":\"Chesterton Deutschland\"},\"image\":{\"@id\":\"https:\\\/\\\/aw-chesterton.eu\\\/cs\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dynamick\u00e1 regulace zat\u00ed\u017een\u00ed Archive - A.W. Chesterton Company \u2013 EU","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aw-chesterton.eu\/cs\/products\/dynamicka-regulace-zatizeni\/","og_locale":"cs_CZ","og_type":"article","og_title":"Dynamick\u00e1 regulace zat\u00ed\u017een\u00ed Archive - A.W. Chesterton Company \u2013 EU","og_url":"https:\/\/aw-chesterton.eu\/cs\/products\/dynamicka-regulace-zatizeni\/","og_site_name":"A.W. Chesterton Company \u2013 EU","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/aw-chesterton.eu\/cs\/products\/dynamicka-regulace-zatizeni\/","url":"https:\/\/aw-chesterton.eu\/cs\/products\/dynamicka-regulace-zatizeni\/","name":"Dynamick\u00e1 regulace zat\u00ed\u017een\u00ed Archive - A.W. Chesterton Company \u2013 EU","isPartOf":{"@id":"https:\/\/aw-chesterton.eu\/cs\/#website"},"breadcrumb":{"@id":"https:\/\/aw-chesterton.eu\/cs\/products\/dynamicka-regulace-zatizeni\/#breadcrumb"},"inLanguage":"cs"},{"@type":"BreadcrumbList","@id":"https:\/\/aw-chesterton.eu\/cs\/products\/dynamicka-regulace-zatizeni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aw-chesterton.eu\/cs\/titulni-strana\/"},{"@type":"ListItem","position":2,"name":"M\u011bkk\u00e9 ucp\u00e1vky a ploch\u00e1 t\u011bsn\u011bn\u00ed","item":"https:\/\/aw-chesterton.eu\/cs\/products\/mekke-ucpavky-a-plocha-tesneni\/"},{"@type":"ListItem","position":3,"name":"Dynamick\u00e1 regulace zat\u00ed\u017een\u00ed"}]},{"@type":"WebSite","@id":"https:\/\/aw-chesterton.eu\/cs\/#website","url":"https:\/\/aw-chesterton.eu\/cs\/","name":"A.W. Chesterton Company \u2013 EU","description":"A.W. Chesterton Company \u2013 EU","publisher":{"@id":"https:\/\/aw-chesterton.eu\/cs\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aw-chesterton.eu\/cs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"cs"},{"@type":"Organization","@id":"https:\/\/aw-chesterton.eu\/cs\/#organization","name":"Chesterton Deutschland","url":"https:\/\/aw-chesterton.eu\/cs\/","logo":{"@type":"ImageObject","inLanguage":"cs","@id":"https:\/\/aw-chesterton.eu\/cs\/#\/schema\/logo\/image\/","url":"https:\/\/aw-chesterton.eu\/wp-content\/uploads\/2026\/03\/Chesterton_Logo_CMYK_Vect.png","contentUrl":"https:\/\/aw-chesterton.eu\/wp-content\/uploads\/2026\/03\/Chesterton_Logo_CMYK_Vect.png","width":1200,"height":218,"caption":"Chesterton Deutschland"},"image":{"@id":"https:\/\/aw-chesterton.eu\/cs\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/aw-chesterton.eu\/cs\/wp-json\/wp\/v2\/product_category\/14093","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aw-chesterton.eu\/cs\/wp-json\/wp\/v2\/product_category"}],"about":[{"href":"https:\/\/aw-chesterton.eu\/cs\/wp-json\/wp\/v2\/taxonomies\/product_category"}],"up":[{"embeddable":true,"href":"https:\/\/aw-chesterton.eu\/cs\/wp-json\/wp\/v2\/product_category\/14028"}],"wp:post_type":[{"href":"https:\/\/aw-chesterton.eu\/cs\/wp-json\/wp\/v2\/chesterton_product?product_category=14093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}